{"id":13,"count":1,"description":"","link":"https:\/\/jma.hastdesigns.com\/index.php\/tag\/witnesses\/","name":"Witnesses","slug":"witnesses","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/jma.hastdesigns.com\/index.php\/wp-json\/wp\/v2\/tags\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jma.hastdesigns.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jma.hastdesigns.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jma.hastdesigns.com\/index.php\/wp-json\/wp\/v2\/posts?tags=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}